{"id":21151,"date":"2023-11-10T14:39:39","date_gmt":"2023-11-10T13:39:39","guid":{"rendered":"https:\/\/grobnik.hr\/event\/hafeneger-renntrainings-6\/"},"modified":"2023-11-10T14:41:02","modified_gmt":"2023-11-10T13:41:02","slug":"hafeneger-renntrainings-6","status":"publish","type":"tribe_events","link":"https:\/\/grobnik.hr\/hr\/event\/hafeneger-renntrainings-6\/","title":{"rendered":"HAFENEGER-RENNTRAININGS"},"content":{"rendered":"<p>Tel: 0049 212 2215003<br \/>\n<a href=\"mailto:info@hafeneger-renntrainings.de\">info@hafeneger-renntrainings.de<\/a><br \/>\n<a href=\"http:\/\/www.hafeneger-renntrainings.de\/\">www.hafeneger-renntrainings.de<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Tel: 0049 212 2215003 info@hafeneger-renntrainings.de www.hafeneger-renntrainings.de<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"footnotes":""},"tags":[],"tribe_events_cat":[69],"class_list":{"0":"post-21151","1":"tribe_events","2":"type-tribe_events","3":"status-publish","5":"tribe_events_cat-moto","6":"cat_moto"},"_links":{"self":[{"href":"https:\/\/grobnik.hr\/hr\/wp-json\/wp\/v2\/tribe_events\/21151","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/grobnik.hr\/hr\/wp-json\/wp\/v2\/tribe_events"}],"about":[{"href":"https:\/\/grobnik.hr\/hr\/wp-json\/wp\/v2\/types\/tribe_events"}],"author":[{"embeddable":true,"href":"https:\/\/grobnik.hr\/hr\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/grobnik.hr\/hr\/wp-json\/wp\/v2\/comments?post=21151"}],"version-history":[{"count":0,"href":"https:\/\/grobnik.hr\/hr\/wp-json\/wp\/v2\/tribe_events\/21151\/revisions"}],"wp:attachment":[{"href":"https:\/\/grobnik.hr\/hr\/wp-json\/wp\/v2\/media?parent=21151"}],"wp:term":[{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/grobnik.hr\/hr\/wp-json\/wp\/v2\/tags?post=21151"},{"taxonomy":"tribe_events_cat","embeddable":true,"href":"https:\/\/grobnik.hr\/hr\/wp-json\/wp\/v2\/tribe_events_cat?post=21151"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}